{"id":16681,"date":"2022-10-14T18:19:58","date_gmt":"2022-10-14T23:19:58","guid":{"rendered":"https:\/\/nuestrostories.com\/?p=16681"},"modified":"2024-03-06T12:54:32","modified_gmt":"2024-03-06T17:54:32","slug":"este-cafe-en-nueva-york-alberga-poesia-latina-innovadora","status":"publish","type":"post","link":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/","title":{"rendered":"Este caf\u00e9 en Nueva York alberga poes\u00eda latina innovadora"},"content":{"rendered":"\n<p><em>Cr\u00e9dito: Nuestro Stories.<\/em><\/p>\n\n\n\n<p>En Nuyorican Poets Caf\u00e9 encontrar\u00e1s el enigm\u00e1tico rostro de <a href=\"https:\/\/www.poetryfoundation.org\/poets\/pedro-pietri\">Pedro Pietri<\/a> junto a otras figuras vestidas con trajes blancos, decorando el mural en East Third Street en Alphabet City.<\/p>\n\n\n\n<p>Nuyorican Poets Caf\u00e9 es ahora un importante punto de encuentro para los artistas latinos en Nueva York y para cualquiera que busque un lugar en donde expresarse a trav\u00e9s del arte.<\/p>\n\n\n\n<p>El caf\u00e9 naci\u00f3 como una necesidad para un grupo de j\u00f3venes latinos en la tumultuosa y ca\u00f3tica Nueva York de los a\u00f1os 70. Todo empez\u00f3 en la sala de estar de <a href=\"https:\/\/www.poetryfoundation.org\/poets\/miguel-algarin\">Miguel Algar\u00edn<\/a>, un puertorrique\u00f1o criado en Lower East Side, con Miguel Pi\u00f1ero, Pedro Pietri y Lucky Cienfuegos: un grupo emergente de poetas que encarnaron la identidad y las luchas de un vecindario predominantemente puertorrique\u00f1o.<\/p>\n\n\n\n<p>La sala de Miguel Algar\u00edn se volvi\u00f3 insuficiente y el grupo empez\u00f3 a rentar un <em>pub <\/em>irland\u00e9s, hasta que, finalmente, a principios de los 80, se instalaron en ese local en East Third Street.<\/p>\n\n\n\n<p><strong>Lee m\u00e1s:<\/strong> <a href=\"https:\/\/nuestrostories.com\/2022\/10\/tito-puente-google-doodle\/\">El ic\u00f3nico Tito Puente, El Rey de los Timbales, obtuvo su propio <em>doodle <\/em>en Google<\/a><\/p>\n\n\n\n<p>A lo largo de las d\u00e9cadas, Nuyorican Poets Caf\u00e9 se ha consolidado como una importante instituci\u00f3n cultural. Alberga recitales de poes\u00eda, sesiones de micr\u00f3fono abierto, conciertos de <em>jazz <\/em>latino y <em>hip-hop<\/em>, representaciones teatrales, programas educativos y exhibiciones de artes visuales.<\/p>\n\n\n\n<p>Esto le ha permitido a Nuyorican Poets Caf\u00e9 recolectar valiosos premios dentro de la comunidad art\u00edstica, como National Poetry Slam en 1998, Zagat Awards of Distinction y Voice Literary Hits Book Award, entre otros.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Once Upon a Time in NuyoRico\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/4kl9z38Sh84?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El caf\u00e9 ha recibido a varias generaciones de artistas de color, incluidos a escritores como <a href=\"https:\/\/www.nancy-mercado.com\/\">Nancy Mercado<\/a>,<a href=\"https:\/\/lithub.com\/paul-beatty-on-los-angeles-lit-the-sellout-and-life-after-the-man-booker\/\"> Paul Beatty<\/a> y <a href=\"https:\/\/www.poetryfoundation.org\/poets\/willie-perdomo\">Willie Perdomo<\/a>, as\u00ed como al cantante Danny Rivera y al rapero MF Doom.<\/li>\n\n\n\n<li>El t\u00e9rmino \u00abnuyorican\u00bb es una mezcla de puertorrique\u00f1o y neoyorquino, o \u00abnuyorrique\u00f1o\u00bb, que fue usado por los puertorrique\u00f1os nacidos en la isla para identificar a los puertorrique\u00f1os de la ciudad de Nueva York.<\/li>\n\n\n\n<li>Nuyorican Poets Caf\u00e9 fue el hogar del activista LGBTQ+ <a href=\"https:\/\/www.poetryfoundation.org\/poets\/emanuel-xavier\">Emanuel Xavier<\/a>.<\/li>\n\n\n\n<li>La poeta dominicanaestadounidense Elizabeth Acevedo, ganadora de National Book Award for Young People&#8217;s Fiction en 2018, hizo su primera aparici\u00f3n en el caf\u00e9 cuando ten\u00eda quince a\u00f1os.<\/li>\n<\/ul>\n\n\n\n<p><strong>Direcci\u00f3n:<\/strong> 236 East 3rd Street.<\/p>\n\n\n\n<p>Experim\u00e9ntalo <a href=\"https:\/\/goo.gl\/maps\/3FRtdsD2YLLZt6PeA\"><strong>aqu\u00ed<\/strong><\/a>.<\/p>\n\n\n\n<p><strong>Por Isaac Vallenilla<\/strong><\/p>\n\n\n\n<p>Isaac Vallenilla es un entusiasta del cine con menci\u00f3n en Lenguas Modernas de la Universidad de los Andes, Venezuela. Trabaja como corrector, traductor y educador desde hace seis a\u00f1os. Actualmente vive en Buenos Aires, Argentina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Nuestro Stories. En Nuyorican Poets Caf\u00e9 encontrar\u00e1s el enigm\u00e1tico rostro de Pedro Pietri junto a otras figuras vestidas con trajes blancos, decorando el mural en East Third Street en Alphabet City. Nuyorican Poets Caf\u00e9 es ahora un importante punto de encuentro para los artistas latinos en Nueva York y para cualquiera que busque un [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":10069,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1319],"tags":[],"class_list":["post-16681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugares-de-interes-latinos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Este caf\u00e9 en Nueva York alberga poes\u00eda latina innovadora - Nuestro Stories<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Este caf\u00e9 en Nueva York alberga poes\u00eda latina innovadora - Nuestro Stories\" \/>\n<meta property=\"og:description\" content=\"Cr\u00e9dito: Nuestro Stories. En Nuyorican Poets Caf\u00e9 encontrar\u00e1s el enigm\u00e1tico rostro de Pedro Pietri junto a otras figuras vestidas con trajes blancos, decorando el mural en East Third Street en Alphabet City. Nuyorican Poets Caf\u00e9 es ahora un importante punto de encuentro para los artistas latinos en Nueva York y para cualquiera que busque un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Stories\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-14T23:19:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-06T17:54:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/10\/Landmark-copy-70.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1910\" \/>\n\t<meta property=\"og:image:height\" content=\"1274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Isaac Vallenilla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isaac Vallenilla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\\\/\"},\"author\":{\"name\":\"Isaac Vallenilla\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#\\\/schema\\\/person\\\/674309bd2373dc181d53e0c0ee41d3ae\"},\"headline\":\"Este caf\u00e9 en Nueva York alberga poes\u00eda latina innovadora\",\"datePublished\":\"2022-10-14T23:19:58+00:00\",\"dateModified\":\"2024-03-06T17:54:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\\\/\"},\"wordCount\":449,\"publisher\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Landmark-copy-70.jpg\",\"articleSection\":[\"LUGARES DE INTER\u00c9S LATINOS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\\\/\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\\\/\",\"name\":\"Este caf\u00e9 en Nueva York alberga poes\u00eda latina innovadora - Nuestro Stories\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Landmark-copy-70.jpg\",\"datePublished\":\"2022-10-14T23:19:58+00:00\",\"dateModified\":\"2024-03-06T17:54:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Landmark-copy-70.jpg\",\"contentUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Landmark-copy-70.jpg\",\"width\":1910,\"height\":1274},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Este caf\u00e9 en Nueva York alberga poes\u00eda latina innovadora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/\",\"name\":\"Nuestro Stories\",\"description\":\"Latino Heritage. Every Day.\",\"publisher\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#organization\",\"name\":\"Nuestro Stories\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Nuestro-Stories-Logo.png\",\"contentUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Nuestro-Stories-Logo.png\",\"width\":282,\"height\":118,\"caption\":\"Nuestro Stories\"},\"image\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#\\\/schema\\\/person\\\/674309bd2373dc181d53e0c0ee41d3ae\",\"name\":\"Isaac Vallenilla\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/saac-Vallenilla-Nuestro-Stories-Writer-Image-96x96.png\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/saac-Vallenilla-Nuestro-Stories-Writer-Image-96x96.png\",\"contentUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/saac-Vallenilla-Nuestro-Stories-Writer-Image-96x96.png\",\"caption\":\"Isaac Vallenilla\"},\"description\":\"Isaac Vallenilla is a cinema enthusiast with a Major in Modern languages from La Universidad de los Andes, Venezuela. He has been working as a proofreader, translator and educator for 6 years. He currently lives in Buenos Aires, Argentina.\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/author\\\/isaac-vallenilla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Este caf\u00e9 en Nueva York alberga poes\u00eda latina innovadora - Nuestro Stories","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/","og_locale":"es_ES","og_type":"article","og_title":"Este caf\u00e9 en Nueva York alberga poes\u00eda latina innovadora - Nuestro Stories","og_description":"Cr\u00e9dito: Nuestro Stories. En Nuyorican Poets Caf\u00e9 encontrar\u00e1s el enigm\u00e1tico rostro de Pedro Pietri junto a otras figuras vestidas con trajes blancos, decorando el mural en East Third Street en Alphabet City. Nuyorican Poets Caf\u00e9 es ahora un importante punto de encuentro para los artistas latinos en Nueva York y para cualquiera que busque un [&hellip;]","og_url":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/","og_site_name":"Nuestro Stories","article_published_time":"2022-10-14T23:19:58+00:00","article_modified_time":"2024-03-06T17:54:32+00:00","og_image":[{"width":1910,"height":1274,"url":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/10\/Landmark-copy-70.jpg","type":"image\/jpeg"}],"author":"Isaac Vallenilla","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Isaac Vallenilla","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/#article","isPartOf":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/"},"author":{"name":"Isaac Vallenilla","@id":"https:\/\/nuestrostories.com\/es\/#\/schema\/person\/674309bd2373dc181d53e0c0ee41d3ae"},"headline":"Este caf\u00e9 en Nueva York alberga poes\u00eda latina innovadora","datePublished":"2022-10-14T23:19:58+00:00","dateModified":"2024-03-06T17:54:32+00:00","mainEntityOfPage":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/"},"wordCount":449,"publisher":{"@id":"https:\/\/nuestrostories.com\/es\/#organization"},"image":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/#primaryimage"},"thumbnailUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/10\/Landmark-copy-70.jpg","articleSection":["LUGARES DE INTER\u00c9S LATINOS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/","url":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/","name":"Este caf\u00e9 en Nueva York alberga poes\u00eda latina innovadora - Nuestro Stories","isPartOf":{"@id":"https:\/\/nuestrostories.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/#primaryimage"},"image":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/#primaryimage"},"thumbnailUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/10\/Landmark-copy-70.jpg","datePublished":"2022-10-14T23:19:58+00:00","dateModified":"2024-03-06T17:54:32+00:00","breadcrumb":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/#primaryimage","url":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/10\/Landmark-copy-70.jpg","contentUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/10\/Landmark-copy-70.jpg","width":1910,"height":1274},{"@type":"BreadcrumbList","@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/este-cafe-en-nueva-york-alberga-poesia-latina-innovadora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nuestrostories.com\/es\/"},{"@type":"ListItem","position":2,"name":"Este caf\u00e9 en Nueva York alberga poes\u00eda latina innovadora"}]},{"@type":"WebSite","@id":"https:\/\/nuestrostories.com\/es\/#website","url":"https:\/\/nuestrostories.com\/es\/","name":"Nuestro Stories","description":"Latino Heritage. Every Day.","publisher":{"@id":"https:\/\/nuestrostories.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuestrostories.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nuestrostories.com\/es\/#organization","name":"Nuestro Stories","url":"https:\/\/nuestrostories.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nuestrostories.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2021\/11\/Nuestro-Stories-Logo.png","contentUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2021\/11\/Nuestro-Stories-Logo.png","width":282,"height":118,"caption":"Nuestro Stories"},"image":{"@id":"https:\/\/nuestrostories.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nuestrostories.com\/es\/#\/schema\/person\/674309bd2373dc181d53e0c0ee41d3ae","name":"Isaac Vallenilla","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2023\/10\/saac-Vallenilla-Nuestro-Stories-Writer-Image-96x96.png","url":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2023\/10\/saac-Vallenilla-Nuestro-Stories-Writer-Image-96x96.png","contentUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2023\/10\/saac-Vallenilla-Nuestro-Stories-Writer-Image-96x96.png","caption":"Isaac Vallenilla"},"description":"Isaac Vallenilla is a cinema enthusiast with a Major in Modern languages from La Universidad de los Andes, Venezuela. He has been working as a proofreader, translator and educator for 6 years. He currently lives in Buenos Aires, Argentina.","url":"https:\/\/nuestrostories.com\/es\/author\/isaac-vallenilla\/"}]}},"_links":{"self":[{"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/posts\/16681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/comments?post=16681"}],"version-history":[{"count":1,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/posts\/16681\/revisions"}],"predecessor-version":[{"id":16682,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/posts\/16681\/revisions\/16682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/media\/10069"}],"wp:attachment":[{"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/media?parent=16681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/categories?post=16681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/tags?post=16681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}