{"id":16944,"date":"2022-10-10T18:37:35","date_gmt":"2022-10-10T23:37:35","guid":{"rendered":"https:\/\/nuestrostories.com\/?p=16944"},"modified":"2024-03-11T09:33:27","modified_gmt":"2024-03-11T14:33:27","slug":"los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo","status":"publish","type":"post","link":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/","title":{"rendered":"Los restos fosilizados originales de El Pueblo Trading Post permanecen en este museo"},"content":{"rendered":"\n<p><em>Cr\u00e9dito: Nuestro Stories.<\/em><\/p>\n\n\n\n<p>El Pueblo History Museum, ubicado en Pueblo, Colorado, es un espacio que re\u00fane lo mejor de todos los mundos cuando se trata de la importancia hist\u00f3rica de los pueblos originarios de la tierra, junto con la multitud de influencias culturales que llegaron en a\u00f1os posteriores, durante las \u00e9pocas de <a href=\"https:\/\/www.nationalgeographic.com\/culture\/article\/colonialism\">la colonizaci\u00f3n<\/a>.<\/p>\n\n\n\n<p>Usando un enfoque \u00fanico para una experiencia muse\u00edstica, El Pueblo alberga una variedad de exhibiciones innovadoras, lo que le brinda al espectador una experiencia mucho m\u00e1s pr\u00e1ctica y tangible que puede aprovechar en su visita. La propiedad incluye la recreaci\u00f3n de un puesto comercial y una plaza de adobe de la d\u00e9cada de 1840; tambi\u00e9n es el hogar del sitio de excavaci\u00f3n arqueol\u00f3gica de El Pueblo Trading Post, que data de 1842.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El prop\u00f3sito de El Pueblo Trading Post\u00a0<\/h2>\n\n\n\n<p>El Pueblo Trading Post fue el primer asentamiento permanente en la tierra ahora conocida como Pueblo, Colorado.<\/p>\n\n\n\n<p>Fue construido con la esperanza de facilitar el comercio de pieles a lo largo del r\u00edo Arkansas. Como sol\u00eda ocurrir con la colonizaci\u00f3n, los pueblos originales de la tierra se sintieron inquietos y descontentos con la gente que se apoderaba de sus tierras y las tensiones aumentaron. Poco m\u00e1s de diez a\u00f1os despu\u00e9s de la construcci\u00f3n del puesto, las tensiones llegaron a un punto cr\u00edtico cuando las tribus ind\u00edgenas intentaron expulsar a los colonizadores, lo que llev\u00f3 a lo que se conoce como la Tragedia de Navidad de 1854. El puesto cay\u00f3 en ruinas despu\u00e9s de ser abandonado y el pueblo creci\u00f3 alrededor de sus restos fosilizados.<\/p>\n\n\n\n<p>El museo tambi\u00e9n act\u00faa como un espacio m\u00e1s comunitario que la mayor\u00eda y ofrece muchas clases para que los ni\u00f1os vuelvan a estar en contacto con sus ra\u00edces culturales y su historia. Cursos como artes ind\u00edgenas modernas, danzas latinoamericanas y m\u00e1s brindan a los ni\u00f1os la oportunidad no solo de conocer un poco de historia, sino tambi\u00e9n de participar en la recuperaci\u00f3n de su herencia.<\/p>\n\n\n\n<p><strong>Lee m\u00e1s:<\/strong> <a href=\"https:\/\/nuestrostories.com\/2022\/05\/ruins-preserve-history-ancestral-pueblo-people\/\">Estas ruinas preservan la historia del pueblo ancestral<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cosas que debes saber antes de ir:<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El Pueblo est\u00e1 abierto de lunes a s\u00e1bado de 10 a.m. a 4 p.m., excepto los d\u00edas festivos nacionales importantes.<\/li>\n\n\n\n<li>Los menores de 18 a\u00f1os entran gratis.<\/li>\n\n\n\n<li>El Pueblo est\u00e1 ubicado en 301 N Union Ave., Pueblo, Colorado.<\/li>\n<\/ul>\n\n\n\n<p><strong>Por Liv Styler<\/strong><\/p>\n\n\n\n<p>Olivia Monahan es una periodista, editora, educadora y organizadora chicana en Sacramento cuyo \u00fanico objetivo es arrojar luz sobre historias de nuestras comunidades m\u00e1s impactadas y marginadas, pero, a\u00fan m\u00e1s importante, que esas historias humanicen a quienes normalmente quedan excluidos. Es finalista de la Beca Ida B Wells de periodismo de investigaci\u00f3n 2022, miembro de Parenting Journalists Society y ha publicado en The Courier, The Sacramento Bee, The Americano y Submerge Magazine, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Nuestro Stories. El Pueblo History Museum, ubicado en Pueblo, Colorado, es un espacio que re\u00fane lo mejor de todos los mundos cuando se trata de la importancia hist\u00f3rica de los pueblos originarios de la tierra, junto con la multitud de influencias culturales que llegaron en a\u00f1os posteriores, durante las \u00e9pocas de la colonizaci\u00f3n. Usando [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10059,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1319],"tags":[],"class_list":["post-16944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugares-de-interes-latinos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los restos fosilizados originales de El Pueblo Trading Post permanecen en este museo - Nuestro Stories<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los restos fosilizados originales de El Pueblo Trading Post permanecen en este museo - Nuestro Stories\" \/>\n<meta property=\"og:description\" content=\"Cr\u00e9dito: Nuestro Stories. El Pueblo History Museum, ubicado en Pueblo, Colorado, es un espacio que re\u00fane lo mejor de todos los mundos cuando se trata de la importancia hist\u00f3rica de los pueblos originarios de la tierra, junto con la multitud de influencias culturales que llegaron en a\u00f1os posteriores, durante las \u00e9pocas de la colonizaci\u00f3n. Usando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Stories\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-10T23:37:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-11T14:33:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/10\/Landmark-copy-68.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1910\" \/>\n\t<meta property=\"og:image:height\" content=\"1274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rachel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rachel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\\\/\"},\"author\":{\"name\":\"Rachel\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#\\\/schema\\\/person\\\/f47422cace2ee5360c765844aa2ab67f\"},\"headline\":\"Los restos fosilizados originales de El Pueblo Trading Post permanecen en este museo\",\"datePublished\":\"2022-10-10T23:37:35+00:00\",\"dateModified\":\"2024-03-11T14:33:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\\\/\"},\"wordCount\":504,\"publisher\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Landmark-copy-68.jpg\",\"articleSection\":[\"LUGARES DE INTER\u00c9S LATINOS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\\\/\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\\\/\",\"name\":\"Los restos fosilizados originales de El Pueblo Trading Post permanecen en este museo - Nuestro Stories\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Landmark-copy-68.jpg\",\"datePublished\":\"2022-10-10T23:37:35+00:00\",\"dateModified\":\"2024-03-11T14:33:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Landmark-copy-68.jpg\",\"contentUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Landmark-copy-68.jpg\",\"width\":1910,\"height\":1274},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/10\\\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los restos fosilizados originales de El Pueblo Trading Post permanecen en este museo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/\",\"name\":\"Nuestro Stories\",\"description\":\"Latino Heritage. Every Day.\",\"publisher\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#organization\",\"name\":\"Nuestro Stories\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Nuestro-Stories-Logo.png\",\"contentUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Nuestro-Stories-Logo.png\",\"width\":282,\"height\":118,\"caption\":\"Nuestro Stories\"},\"image\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#\\\/schema\\\/person\\\/f47422cace2ee5360c765844aa2ab67f\",\"name\":\"Rachel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/RachelBio-150x150.jpg\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/RachelBio-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/RachelBio-150x150.jpg\",\"caption\":\"Rachel\"},\"description\":\"Olivia Monahan Chicana journalist, editor, educator, and organizer in Sacramento whose sole focus is to shed light on stories on our most impacted and marginalized communities, but even more importantly, for those stories to humanize those normally left out. She is an Ida B Wells Investigative Journalism Fellow 2022 Finalist, a member of the Parenting Journalists Society, and has bylines in The Courier, The Sacramento Bee, The Americano, Submerge Magazine among others.\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/author\\\/rachel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los restos fosilizados originales de El Pueblo Trading Post permanecen en este museo - Nuestro Stories","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/","og_locale":"es_ES","og_type":"article","og_title":"Los restos fosilizados originales de El Pueblo Trading Post permanecen en este museo - Nuestro Stories","og_description":"Cr\u00e9dito: Nuestro Stories. El Pueblo History Museum, ubicado en Pueblo, Colorado, es un espacio que re\u00fane lo mejor de todos los mundos cuando se trata de la importancia hist\u00f3rica de los pueblos originarios de la tierra, junto con la multitud de influencias culturales que llegaron en a\u00f1os posteriores, durante las \u00e9pocas de la colonizaci\u00f3n. Usando [&hellip;]","og_url":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/","og_site_name":"Nuestro Stories","article_published_time":"2022-10-10T23:37:35+00:00","article_modified_time":"2024-03-11T14:33:27+00:00","og_image":[{"width":1910,"height":1274,"url":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/10\/Landmark-copy-68.jpg","type":"image\/jpeg"}],"author":"Rachel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rachel","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/#article","isPartOf":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/"},"author":{"name":"Rachel","@id":"https:\/\/nuestrostories.com\/es\/#\/schema\/person\/f47422cace2ee5360c765844aa2ab67f"},"headline":"Los restos fosilizados originales de El Pueblo Trading Post permanecen en este museo","datePublished":"2022-10-10T23:37:35+00:00","dateModified":"2024-03-11T14:33:27+00:00","mainEntityOfPage":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/"},"wordCount":504,"publisher":{"@id":"https:\/\/nuestrostories.com\/es\/#organization"},"image":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/#primaryimage"},"thumbnailUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/10\/Landmark-copy-68.jpg","articleSection":["LUGARES DE INTER\u00c9S LATINOS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/","url":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/","name":"Los restos fosilizados originales de El Pueblo Trading Post permanecen en este museo - Nuestro Stories","isPartOf":{"@id":"https:\/\/nuestrostories.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/#primaryimage"},"image":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/#primaryimage"},"thumbnailUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/10\/Landmark-copy-68.jpg","datePublished":"2022-10-10T23:37:35+00:00","dateModified":"2024-03-11T14:33:27+00:00","breadcrumb":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/#primaryimage","url":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/10\/Landmark-copy-68.jpg","contentUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/10\/Landmark-copy-68.jpg","width":1910,"height":1274},{"@type":"BreadcrumbList","@id":"https:\/\/nuestrostories.com\/es\/2022\/10\/los-restos-fosilizados-originales-de-el-pueblo-trading-post-permanecen-en-este-museo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nuestrostories.com\/es\/"},{"@type":"ListItem","position":2,"name":"Los restos fosilizados originales de El Pueblo Trading Post permanecen en este museo"}]},{"@type":"WebSite","@id":"https:\/\/nuestrostories.com\/es\/#website","url":"https:\/\/nuestrostories.com\/es\/","name":"Nuestro Stories","description":"Latino Heritage. Every Day.","publisher":{"@id":"https:\/\/nuestrostories.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuestrostories.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nuestrostories.com\/es\/#organization","name":"Nuestro Stories","url":"https:\/\/nuestrostories.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nuestrostories.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2021\/11\/Nuestro-Stories-Logo.png","contentUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2021\/11\/Nuestro-Stories-Logo.png","width":282,"height":118,"caption":"Nuestro Stories"},"image":{"@id":"https:\/\/nuestrostories.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nuestrostories.com\/es\/#\/schema\/person\/f47422cace2ee5360c765844aa2ab67f","name":"Rachel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2023\/06\/RachelBio-150x150.jpg","url":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2023\/06\/RachelBio-150x150.jpg","contentUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2023\/06\/RachelBio-150x150.jpg","caption":"Rachel"},"description":"Olivia Monahan Chicana journalist, editor, educator, and organizer in Sacramento whose sole focus is to shed light on stories on our most impacted and marginalized communities, but even more importantly, for those stories to humanize those normally left out. She is an Ida B Wells Investigative Journalism Fellow 2022 Finalist, a member of the Parenting Journalists Society, and has bylines in The Courier, The Sacramento Bee, The Americano, Submerge Magazine among others.","url":"https:\/\/nuestrostories.com\/es\/author\/rachel\/"}]}},"_links":{"self":[{"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/posts\/16944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/comments?post=16944"}],"version-history":[{"count":1,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/posts\/16944\/revisions"}],"predecessor-version":[{"id":16945,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/posts\/16944\/revisions\/16945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/media\/10059"}],"wp:attachment":[{"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/media?parent=16944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/categories?post=16944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/tags?post=16944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}