{"id":17341,"date":"2022-09-20T17:44:04","date_gmt":"2022-09-20T22:44:04","guid":{"rendered":"https:\/\/nuestrostories.com\/?p=17341"},"modified":"2024-03-19T20:22:32","modified_gmt":"2024-03-20T01:22:32","slug":"todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana","status":"publish","type":"post","link":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/","title":{"rendered":"Todo por Selena: Este museo en Corpus Christi rinde homenaje a la reina de la m\u00fasica texana"},"content":{"rendered":"<p><i><span style=\"font-weight: 400;\">Cr\u00e9dito: Nuestro Stories<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Desde el auto que conduc\u00eda hasta los bustiers que enfurec\u00edan a su padre, pasando por su pionero Grammy, puedes encontrar un poco de todo en el museo de Selena Quintanilla en su ciudad natal de Corpus Christi, Texas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El museo alberga la colecci\u00f3n m\u00e1s grande del pa\u00eds de recuerdos relacionados con Selena.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Selena fue la reina de la m\u00fasica texana que encabez\u00f3 las listas, bati\u00f3 r\u00e9cords y marc\u00f3 tendencias, y tuvo un impacto duradero en el mundo con su interpretaci\u00f3n de la m\u00fasica tradicional mexicana y su capacidad para encabezar las listas de Billboard tanto en ingl\u00e9s como en espa\u00f1ol, una haza\u00f1a que a\u00fan no se hab\u00eda logrado. Fue la primera estrella <\/span><i><span style=\"font-weight: 400;\">crossover<\/span><\/i><span style=\"font-weight: 400;\"> de la industria musical mexicana.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Su carrera comenz\u00f3 temprano con una banda familiar llamada<\/span> <i><span style=\"font-weight: 400;\">Selena y los Dinos.<\/span><\/i> <span style=\"font-weight: 400;\">Su juventud (era la menor de la familia Quintanilla), adem\u00e1s de ser una mujer en una industria centrada en los hombres, la puso frente a bastantes obst\u00e1culos, pero su tes\u00f3n junto con el aliento de su familia la llevaron a continuar. Consigui\u00f3 un contrato discogr\u00e1fico con EMI Latin en 1989. El trato se produjo dos a\u00f1os despu\u00e9s de que ganara el premio a Vocalista Femenina del A\u00f1o en los Tejano Music Awards.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>Lee m\u00e1s:<\/b> <a href=\"https:\/\/nuestrostories.com\/2022\/06\/review-smithsonian-first-ever-latino-history-exhibit\/\"><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">Historia de las calificaciones: Una revisi\u00f3n de la primera exposici\u00f3n de historia latina del Smithsonian<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">La carrera de Selena se dispar\u00f3 r\u00e1pidamente, lo que llev\u00f3 a que sus sencillos encabezaran las listas de Billboard como <\/span><i><span style=\"font-weight: 400;\">Como la flor.<\/span><\/i> <span style=\"font-weight: 400;\">Adem\u00e1s de su carrera musical, su sentido de la moda inspir\u00f3 a mujeres de todo el mundo, lo que la impuls\u00f3 a iniciar su propia l\u00ednea de moda basada en sus gustos personales. Como inspiraci\u00f3n para millones de personas, Selena era pr\u00e1cticamente una santa patrona de las mujeres y ni\u00f1as mexicanas y chicanas que segu\u00edan cada uno de sus movimientos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Su carrera y su vida quedaron tr\u00e1gicamente truncadas cuando fue asesinada por Yolanda Sald\u00edvar el 31 de marzo de 1995. Ten\u00eda apenas 23 a\u00f1os.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Sald\u00edvar, el monstruo<\/span><\/h2>\n<p><a href=\"https:\/\/www.ksat.com\/news\/local\/2021\/07\/08\/yolanda-saldivar-could-be-released-as-soon-as-2025\/\"><span style=\"font-weight: 400;\">Yolanda Sald\u00edvar<\/span><\/a> <span style=\"font-weight: 400;\">hab\u00eda sido nombrada gerente de las boutiques de Selena a principios de 1994, as\u00ed como presidenta y gerente del club de fans de Selena. Sald\u00edvar mostr\u00f3 devoci\u00f3n por la familia Quintanilla, especialmente por Selena, desde el principio. Esa devoci\u00f3n aparentemente se convirti\u00f3 en una obsesi\u00f3n de Sald\u00edvar que se manifest\u00f3 en multitud de formas poco saludables.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando se descubri\u00f3 que Sald\u00edvar hab\u00eda malversado decenas de miles de d\u00f3lares del club de fans, miembros de la familia Quintanilla confrontaron a Sald\u00edvar, exigi\u00e9ndole que proporcionara pruebas que refutaran las acusaciones, o se involucrar\u00eda a la polic\u00eda. Aunque se le prohibi\u00f3 hablar con Selena, Selena intent\u00f3 mantener abiertas las l\u00edneas de comunicaci\u00f3n con Sald\u00edvar. Selena sab\u00eda que Sald\u00edvar ten\u00eda los registros financieros que la empresa necesitaba para efectos fiscales y quer\u00eda obtener la documentaci\u00f3n antes de romper los v\u00ednculos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Selena se reuni\u00f3 con Sald\u00edvar en un motel de Corpus Christi y le exigi\u00f3 los papeles. Enfurecida, Sald\u00edvar sac\u00f3 un arma de su bolso y le dispar\u00f3 a Selena una vez mientras intentaba salir corriendo de la habitaci\u00f3n. La bala alcanz\u00f3 a la cantante en el hombro, lo que normalmente es un disparo que permite sobrevivir. Desafortunadamente, la bala que dispar\u00f3 Sald\u00edvar cort\u00f3 la arteria subclavia, lo que provoc\u00f3 que Selena perdiera demasiada sangre para que pudiera recuperarse.<\/span><span style=\"font-size: revert; color: initial; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">El legado de Selena permanece intacto<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">El Selena Museum, que su familia abri\u00f3 en respuesta al deseo de sus fans de honrar a la ic\u00f3nica cantante, se ha convertido en una de las atracciones tur\u00edsticas m\u00e1s populares del sur de Texas<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<figure id=\"attachment_6564\" aria-describedby=\"caption-attachment-6564\" style=\"width: 799px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6564\" src=\"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/bv-nm.png\" alt=\"Anything for Selenas: This Corpus Christi Museum Honors the Queen of Tejano Music nuestro stories \" width=\"799\" height=\"497\" srcset=\"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/bv-nm.png 1600w, https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/bv-nm-300x187.png 300w, https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/bv-nm-1024x637.png 1024w, https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/bv-nm-768x478.png 768w, https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/bv-nm-1536x955.png 1536w, https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/bv-nm-200x124.png 200w, https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/bv-nm-400x249.png 400w, https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/bv-nm-600x373.png 600w, https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/bv-nm-800x498.png 800w, https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/bv-nm-1200x746.png 1200w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><figcaption id=\"caption-attachment-6564\" class=\"wp-caption-text\"><em>Cr\u00e9dito: Google Earth<\/em><\/figcaption><\/figure>\n<h2><span style=\"font-weight: 400;\">Cosas que debes saber antes de ir:<\/span><\/h2>\n<ul>\n<li><span style=\"font-weight: 400;\">El Museo Selena abre de 10 a.m. a 4 p.m., de lunes a viernes.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">M\u00e1s de 30,000 personas visitan el museo cada a\u00f1o.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">La entrada a la exposici\u00f3n completa cuesta 3 d\u00f3lares por persona.<\/span><\/li>\n<\/ul>\n<p><a href=\"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/06\/Liv-182%C3%97250.jpeg\"><span style=\"font-weight: 400;\">https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/06\/Liv-182\u00d7250.jpeg<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Por Liv Styler<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Olivia Monahan \u2013 Periodista, editora, educadora y organizadora chicana en Sacramento cuyo \u00fanico objetivo es arrojar luz sobre historias de nuestras comunidades m\u00e1s impactadas y marginadas pero, a\u00fan m\u00e1s importante, que esas historias humanicen a quienes normalmente quedan excluidos. Es finalista de la Beca Ida B Wells de periodismo de investigaci\u00f3n 2022, miembro de la Parenting Journalists Society y ha publicado en The Courier, The Sacramento Bee, The Americano y Submerge Magazine, entre otros.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Nuestro Stories Desde el auto que conduc\u00eda hasta los bustiers que enfurec\u00edan a su padre, pasando por su pionero Grammy, puedes encontrar un poco de todo en el museo de Selena Quintanilla en su ciudad natal de Corpus Christi, Texas. El museo alberga la colecci\u00f3n m\u00e1s grande del pa\u00eds de recuerdos relacionados con Selena. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10024,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1319],"tags":[],"class_list":["post-17341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugares-de-interes-latinos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Todo por Selena: Este museo en Corpus Christi rinde homenaje a la reina de la m\u00fasica texana - Nuestro Stories<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todo por Selena: Este museo en Corpus Christi rinde homenaje a la reina de la m\u00fasica texana - Nuestro Stories\" \/>\n<meta property=\"og:description\" content=\"Cr\u00e9dito: Nuestro Stories Desde el auto que conduc\u00eda hasta los bustiers que enfurec\u00edan a su padre, pasando por su pionero Grammy, puedes encontrar un poco de todo en el museo de Selena Quintanilla en su ciudad natal de Corpus Christi, Texas. El museo alberga la colecci\u00f3n m\u00e1s grande del pa\u00eds de recuerdos relacionados con Selena. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Stories\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-20T22:44:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-20T01:22:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/Landmark-copy-58.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1910\" \/>\n\t<meta property=\"og:image:height\" content=\"1274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rachel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rachel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/09\\\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/09\\\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\\\/\"},\"author\":{\"name\":\"Rachel\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#\\\/schema\\\/person\\\/f47422cace2ee5360c765844aa2ab67f\"},\"headline\":\"Todo por Selena: Este museo en Corpus Christi rinde homenaje a la reina de la m\u00fasica texana\",\"datePublished\":\"2022-09-20T22:44:04+00:00\",\"dateModified\":\"2024-03-20T01:22:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/09\\\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\\\/\"},\"wordCount\":810,\"publisher\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/09\\\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Landmark-copy-58.jpg\",\"articleSection\":[\"LUGARES DE INTER\u00c9S LATINOS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/09\\\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\\\/\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/09\\\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\\\/\",\"name\":\"Todo por Selena: Este museo en Corpus Christi rinde homenaje a la reina de la m\u00fasica texana - Nuestro Stories\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/09\\\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/09\\\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Landmark-copy-58.jpg\",\"datePublished\":\"2022-09-20T22:44:04+00:00\",\"dateModified\":\"2024-03-20T01:22:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/09\\\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/09\\\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/09\\\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Landmark-copy-58.jpg\",\"contentUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Landmark-copy-58.jpg\",\"width\":1910,\"height\":1274},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/2022\\\/09\\\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todo por Selena: Este museo en Corpus Christi rinde homenaje a la reina de la m\u00fasica texana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/\",\"name\":\"Nuestro Stories\",\"description\":\"Latino Heritage. Every Day.\",\"publisher\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#organization\",\"name\":\"Nuestro Stories\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Nuestro-Stories-Logo.png\",\"contentUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Nuestro-Stories-Logo.png\",\"width\":282,\"height\":118,\"caption\":\"Nuestro Stories\"},\"image\":{\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/#\\\/schema\\\/person\\\/f47422cace2ee5360c765844aa2ab67f\",\"name\":\"Rachel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/RachelBio-150x150.jpg\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/RachelBio-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/nuestrostories.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/RachelBio-150x150.jpg\",\"caption\":\"Rachel\"},\"description\":\"Olivia Monahan Chicana journalist, editor, educator, and organizer in Sacramento whose sole focus is to shed light on stories on our most impacted and marginalized communities, but even more importantly, for those stories to humanize those normally left out. She is an Ida B Wells Investigative Journalism Fellow 2022 Finalist, a member of the Parenting Journalists Society, and has bylines in The Courier, The Sacramento Bee, The Americano, Submerge Magazine among others.\",\"url\":\"https:\\\/\\\/nuestrostories.com\\\/es\\\/author\\\/rachel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todo por Selena: Este museo en Corpus Christi rinde homenaje a la reina de la m\u00fasica texana - Nuestro Stories","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/","og_locale":"es_ES","og_type":"article","og_title":"Todo por Selena: Este museo en Corpus Christi rinde homenaje a la reina de la m\u00fasica texana - Nuestro Stories","og_description":"Cr\u00e9dito: Nuestro Stories Desde el auto que conduc\u00eda hasta los bustiers que enfurec\u00edan a su padre, pasando por su pionero Grammy, puedes encontrar un poco de todo en el museo de Selena Quintanilla en su ciudad natal de Corpus Christi, Texas. El museo alberga la colecci\u00f3n m\u00e1s grande del pa\u00eds de recuerdos relacionados con Selena. [&hellip;]","og_url":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/","og_site_name":"Nuestro Stories","article_published_time":"2022-09-20T22:44:04+00:00","article_modified_time":"2024-03-20T01:22:32+00:00","og_image":[{"width":1910,"height":1274,"url":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/Landmark-copy-58.jpg","type":"image\/jpeg"}],"author":"Rachel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rachel","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/#article","isPartOf":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/"},"author":{"name":"Rachel","@id":"https:\/\/nuestrostories.com\/es\/#\/schema\/person\/f47422cace2ee5360c765844aa2ab67f"},"headline":"Todo por Selena: Este museo en Corpus Christi rinde homenaje a la reina de la m\u00fasica texana","datePublished":"2022-09-20T22:44:04+00:00","dateModified":"2024-03-20T01:22:32+00:00","mainEntityOfPage":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/"},"wordCount":810,"publisher":{"@id":"https:\/\/nuestrostories.com\/es\/#organization"},"image":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/#primaryimage"},"thumbnailUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/Landmark-copy-58.jpg","articleSection":["LUGARES DE INTER\u00c9S LATINOS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/","url":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/","name":"Todo por Selena: Este museo en Corpus Christi rinde homenaje a la reina de la m\u00fasica texana - Nuestro Stories","isPartOf":{"@id":"https:\/\/nuestrostories.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/#primaryimage"},"image":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/#primaryimage"},"thumbnailUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/Landmark-copy-58.jpg","datePublished":"2022-09-20T22:44:04+00:00","dateModified":"2024-03-20T01:22:32+00:00","breadcrumb":{"@id":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/#primaryimage","url":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/Landmark-copy-58.jpg","contentUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2022\/09\/Landmark-copy-58.jpg","width":1910,"height":1274},{"@type":"BreadcrumbList","@id":"https:\/\/nuestrostories.com\/es\/2022\/09\/todo-por-selena-este-museo-en-corpus-christi-rinde-homenaje-a-la-reina-de-la-musica-texana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nuestrostories.com\/es\/"},{"@type":"ListItem","position":2,"name":"Todo por Selena: Este museo en Corpus Christi rinde homenaje a la reina de la m\u00fasica texana"}]},{"@type":"WebSite","@id":"https:\/\/nuestrostories.com\/es\/#website","url":"https:\/\/nuestrostories.com\/es\/","name":"Nuestro Stories","description":"Latino Heritage. Every Day.","publisher":{"@id":"https:\/\/nuestrostories.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuestrostories.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nuestrostories.com\/es\/#organization","name":"Nuestro Stories","url":"https:\/\/nuestrostories.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nuestrostories.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2021\/11\/Nuestro-Stories-Logo.png","contentUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2021\/11\/Nuestro-Stories-Logo.png","width":282,"height":118,"caption":"Nuestro Stories"},"image":{"@id":"https:\/\/nuestrostories.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nuestrostories.com\/es\/#\/schema\/person\/f47422cace2ee5360c765844aa2ab67f","name":"Rachel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2023\/06\/RachelBio-150x150.jpg","url":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2023\/06\/RachelBio-150x150.jpg","contentUrl":"https:\/\/nuestrostories.com\/wp-content\/uploads\/2023\/06\/RachelBio-150x150.jpg","caption":"Rachel"},"description":"Olivia Monahan Chicana journalist, editor, educator, and organizer in Sacramento whose sole focus is to shed light on stories on our most impacted and marginalized communities, but even more importantly, for those stories to humanize those normally left out. She is an Ida B Wells Investigative Journalism Fellow 2022 Finalist, a member of the Parenting Journalists Society, and has bylines in The Courier, The Sacramento Bee, The Americano, Submerge Magazine among others.","url":"https:\/\/nuestrostories.com\/es\/author\/rachel\/"}]}},"_links":{"self":[{"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/posts\/17341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/comments?post=17341"}],"version-history":[{"count":1,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/posts\/17341\/revisions"}],"predecessor-version":[{"id":17342,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/posts\/17341\/revisions\/17342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/media\/10024"}],"wp:attachment":[{"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/media?parent=17341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/categories?post=17341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nuestrostories.com\/es\/wp-json\/wp\/v2\/tags?post=17341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}